{"id":10235,"date":"2023-12-20T14:23:42","date_gmt":"2023-12-20T10:23:42","guid":{"rendered":"https:\/\/vita-xpro.com\/?post_type=docs&#038;p=10235"},"modified":"2024-12-16T11:59:45","modified_gmt":"2024-12-16T07:59:45","password":"","slug":"vat-api","status":"publish","type":"docs","link":"https:\/\/vita-xpro.com\/ar\/docs\/vat-api\/","title":{"rendered":"VAT API"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"10235\" class=\"elementor elementor-10235\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-56015a33 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"56015a33\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7f521375\" data-id=\"7f521375\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8875bdd elementor-widget elementor-widget-spacer\" data-id=\"8875bdd\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 26-05-2024 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container{height:100%;width:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty,.e-con>.elementor-widget-spacer.elementor-widget-empty{position:relative;min-height:22px;min-width:22px}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon,.e-con>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon{position:absolute;top:0;bottom:0;left:0;right:0;margin:auto;padding:0;width:22px;height:22px}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-061b127 elementor-widget elementor-widget-heading\" data-id=\"061b127\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 26-05-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">VAT API<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35cca7e elementor-widget elementor-widget-spacer\" data-id=\"35cca7e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b54fc15 elementor-widget elementor-widget-text-editor\" data-id=\"4b54fc15\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 26-05-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p><!-- wp:paragraph --><\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>All requests require the user authentication token in the request header.<\/p>\n<p>\u00a0<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p><b>1. URL:<\/b> <a href=\"http:\/\/ {{Host-Name}}\/FileUpload\/ImportFromExcel\" data-wplink-url-error=\"true\">http:\/\/ {{Host-Name}}\/FileUpload\/ImportFromExcel<\/a><\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p><b>2. Method:<\/b> Post<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p><!-- \/wp:paragraph --><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3cf827c elementor-widget elementor-widget-accordion\" data-id=\"3cf827c\" data-element_type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 26-05-2024 *\/\n.elementor-accordion{text-align:start}.elementor-accordion .elementor-accordion-item{border:1px solid #d5d8dc}.elementor-accordion .elementor-accordion-item+.elementor-accordion-item{border-top:none}.elementor-accordion .elementor-tab-title{margin:0;padding:15px 20px;font-weight:700;line-height:1;cursor:pointer;outline:none}.elementor-accordion .elementor-tab-title .elementor-accordion-icon{display:inline-block;width:1.5em}.elementor-accordion .elementor-tab-title .elementor-accordion-icon svg{width:1em;height:1em}.elementor-accordion .elementor-tab-title .elementor-accordion-icon.elementor-accordion-icon-right{float:right;text-align:right}.elementor-accordion .elementor-tab-title .elementor-accordion-icon.elementor-accordion-icon-left{float:left;text-align:left}.elementor-accordion .elementor-tab-title .elementor-accordion-icon .elementor-accordion-icon-closed{display:block}.elementor-accordion .elementor-tab-title .elementor-accordion-icon .elementor-accordion-icon-opened,.elementor-accordion .elementor-tab-title.elementor-active .elementor-accordion-icon-closed{display:none}.elementor-accordion .elementor-tab-title.elementor-active .elementor-accordion-icon-opened{display:block}.elementor-accordion .elementor-tab-content{display:none;padding:15px 20px;border-top:1px solid #d5d8dc}@media (max-width:767px){.elementor-accordion .elementor-tab-title{padding:12px 15px}.elementor-accordion .elementor-tab-title .elementor-accordion-icon{width:1.2em}.elementor-accordion .elementor-tab-content{padding:7px 15px}}.e-con-inner>.elementor-widget-accordion,.e-con>.elementor-widget-accordion{width:var(--container-widget-width);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6391\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-6391\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Request Parameters<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6391\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-6391\"><p>{<\/p>\n<p>&#8220;file&#8221;: &#8220;binary&#8221;,<\/p>\n<p>&#8221; fileType &#8220;:&#8221; int&#8221;,<\/p>\n<p>&#8221; fromDate &#8220;: &#8220;DateTime&#8221;,<\/p>\n<p>&#8221; toDate &#8220;: &#8220;DateTime&#8221;,<\/p>\n<p>&#8220;id&#8221;: &#8220;int&#8221;,<\/p>\n<p>}<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6392\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-6392\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">200: Success<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6392\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-6392\"><p>{<\/p>\n<p>&#8220;result&#8221;: {},<\/p>\n<p>&#8220;targetUrl&#8221;: null,<\/p>\n<p>&#8220;success&#8221;: true,<\/p>\n<p>&#8220;error&#8221;: null,<\/p>\n<p>&#8220;unAuthorizedRequest&#8221;: false,<\/p>\n<p>&#8220;__abp&#8221;: true<\/p>\n<p>}<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6393\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-6393\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">400 \u2013 Bad Request (file Upload Failed<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6393\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-6393\"><p>{<\/p>\n<p>&#8220;result&#8221;: {},<\/p>\n<p>&#8220;targetUrl&#8221;: null,<\/p>\n<p>&#8220;success&#8221;: true,<\/p>\n<p>&#8220;error&#8221;: null,<\/p>\n<p>&#8220;unAuthorizedRequest&#8221;: false,<\/p>\n<p>&#8220;__abp&#8221;: true<\/p>\n<p>}<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6394\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-6394\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">401 \u2013 Unauthorized<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-6394\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-6394\"><p>{<\/p>\n<p>&#8220;result&#8221;: null,<\/p>\n<p>&#8220;targetUrl&#8221;: null,<\/p>\n<p>&#8220;success&#8221;: false,<\/p>\n<p>&#8220;error&#8221;: {<\/p>\n<p>&#8220;code&#8221;: 0,<\/p>\n<p>&#8220;message&#8221;: &#8220;Current user did not login to the application!&#8221;,<\/p>\n<p>&#8220;details&#8221;: null,<\/p>\n<p>&#8220;validationErrors&#8221;: null<\/p>\n<p>},<\/p>\n<p>&#8220;unAuthorizedRequest&#8221;: true,<\/p>\n<p>&#8220;__abp&#8221;: true<\/p>\n<p>}<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>VAT API All requests require the user authentication token in the request header. \u00a0 1. URL: http:\/\/ {{Host-Name}}\/FileUpload\/ImportFromExcel 2. Method: Post Request Parameters { &#8220;file&#8221;: &#8220;binary&#8221;, &#8221; fileType &#8220;:&#8221; int&#8221;, &#8221; fromDate &#8220;: &#8220;DateTime&#8221;, &#8221; toDate &#8220;: &#8220;DateTime&#8221;, &#8220;id&#8221;: &#8220;int&#8221;, } 200: Success { &#8220;result&#8221;: {}, &#8220;targetUrl&#8221;: null, &#8220;success&#8221;: true, &#8220;error&#8221;: null, &#8220;unAuthorizedRequest&#8221;: false, &#8220;__abp&#8221;: [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_eb_attr":"","footnotes":""},"doc_category":[96],"doc_tag":[],"knowledge_base":[],"class_list":["post-10235","docs","type-docs","status-publish","hentry","doc_category-vitaapidocs"],"year_month":"2026-05","word_count":352,"total_views":"1130","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"admin","author_nicename":"vita","author_url":"https:\/\/vita-xpro.com\/ar\/author\/vita\/"},"doc_category_info":[{"term_name":"VITA API Documentation","term_url":"https:\/\/vita-xpro.com\/ar\/docs-category\/vitaapidocs\/"}],"doc_tag_info":[],"_links":{"self":[{"href":"https:\/\/vita-xpro.com\/ar\/wp-json\/wp\/v2\/docs\/10235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vita-xpro.com\/ar\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/vita-xpro.com\/ar\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/vita-xpro.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vita-xpro.com\/ar\/wp-json\/wp\/v2\/comments?post=10235"}],"version-history":[{"count":34,"href":"https:\/\/vita-xpro.com\/ar\/wp-json\/wp\/v2\/docs\/10235\/revisions"}],"predecessor-version":[{"id":12525,"href":"https:\/\/vita-xpro.com\/ar\/wp-json\/wp\/v2\/docs\/10235\/revisions\/12525"}],"wp:attachment":[{"href":"https:\/\/vita-xpro.com\/ar\/wp-json\/wp\/v2\/media?parent=10235"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/vita-xpro.com\/ar\/wp-json\/wp\/v2\/doc_category?post=10235"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/vita-xpro.com\/ar\/wp-json\/wp\/v2\/doc_tag?post=10235"},{"taxonomy":"knowledge_base","embeddable":true,"href":"https:\/\/vita-xpro.com\/ar\/wp-json\/wp\/v2\/knowledge_base?post=10235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}