{"id":11356,"date":"2024-03-12T10:10:08","date_gmt":"2024-03-12T06:10:08","guid":{"rendered":"https:\/\/vita-xpro.com\/?post_type=docs&#038;p=11356"},"modified":"2024-05-08T10:38:09","modified_gmt":"2024-05-08T06:38:09","password":"","slug":"a-sales-invoice-is-a-document-that-is-used-to-record-the-sale-of-goods-or-services-it-includes-information-about-the-customer-the-goods-or-services-that-were-sold-and-the-amount-that-was","status":"publish","type":"docs","link":"https:\/\/vita-xpro.com\/ar\/docs\/a-sales-invoice-is-a-document-that-is-used-to-record-the-sale-of-goods-or-services-it-includes-information-about-the-customer-the-goods-or-services-that-were-sold-and-the-amount-that-was\/","title":{"rendered":"\u0627\u0644\u0645\u0631\u062d\u0644\u0629 \u0627\u0644\u0623\u0648\u0644\u0649 \u0644\u0644\u0641\u0648\u062a\u0631\u0629 \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a\u0629 \u0641\u064a \u0627\u0644\u0645\u0645\u0644\u0643\u0629 \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0627\u0644\u0633\u0639\u0648\u062f\u064a\u0629"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"11356\" class=\"elementor elementor-11356\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5014893 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5014893\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-66b87551\" data-id=\"66b87551\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d258e47 elementor-widget elementor-widget-heading\" data-id=\"2d258e47\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 26-05-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h4 class=\"elementor-heading-title elementor-size-default\">Frequently Asked Questions<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64c172fb elementor-widget elementor-widget-image\" data-id=\"64c172fb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 26-05-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/vita-xpro.com\/wp-content\/uploads\/2024\/02\/FAQs-pana.svg\" class=\"attachment-full size-full wp-image-11079\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8651608 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8651608\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-92aac5c\" data-id=\"92aac5c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a1d7cb6 elementor-widget elementor-widget-heading\" data-id=\"a1d7cb6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Phase I of KSA e-Invoicing<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca261df elementor-widget elementor-widget-ucaddon_unlimited_timeline\" data-id=\"ca261df\" data-element_type=\"widget\" data-widget_type=\"ucaddon_unlimited_timeline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Unlimited Timeline -->\n\n<style>\/* widget: Unlimited Timeline *\/\n\n\r\n@keyframes uc_unlimited_timeline_elementor_ca261df__item-animation {\r\n  0% {\r\n            transform: translateY(100px);\r\n        \t        \tfilter: blur(10px);\r\n\t\t\t\r\n    \t    opacity: 0;\r\n  }\r\n  100% {\r\n            transform: translateY(0px);\r\n        \t            filter: blur(0px);\r\n            \r\n    \t\topacity: 1;\r\n  }\r\n}\r\n\r\n\r\n#uc_unlimited_timeline_elementor_ca261df .ue_timeline_item{\r\n\topacity:0;\r\n}\r\n\r\n\r\n#uc_unlimited_timeline_elementor_ca261df .uc-entrance-animate {\r\n  opacity:1;\r\n}\r\n\r\n#uc_unlimited_timeline_elementor_ca261df .uc-entrance-animate {\r\n\tanimation: uc_unlimited_timeline_elementor_ca261df__item-animation 1.003s cubic-bezier(0.470, 0.000, 0.745, 0.715) both;\r\n}\r\n\r\n\t\t\t\n\n#uc_unlimited_timeline_elementor_ca261df{\n  direction:rtl;\n}\n\n#uc_unlimited_timeline_elementor_ca261df *{\n  box-sizing:border-box;\n}\n\n#uc_unlimited_timeline_elementor_ca261df .ue_timeline_item{\n  display:flex;\n  flex-direction:row-reverse;\n}\n\n#uc_unlimited_timeline_elementor_ca261df .ue_timeline_item_icon{\n  display:flex;\n  flex-direction:column;\n  align-items:center;\n}\n\n#uc_unlimited_timeline_elementor_ca261df .ue_timeline_item_icon_line{\n  flex-grow:1;\n}\n\n#uc_unlimited_timeline_elementor_ca261df .ue_timeline_item_icon_line_offset{\n  flex-grow:0;\n  flex-shrink:0;\n}\n\n#uc_unlimited_timeline_elementor_ca261df .ue_timeline_item_icon_holder{\n  display:flex;\n  justify-content:center;\n  align-items:center;\n  line-height:1em;\n  flex-direction:column;\n  transition: all 0.4s ease-in-out;\n  text-align: center;\n}\n\n#uc_unlimited_timeline_elementor_ca261df .ue_timeline_item_icon_holder svg{\n  height:1em;\n  width:1em;\n}\n\n#uc_unlimited_timeline_elementor_ca261df .ue_timeline_item_content{\n  flex:1;\n  flex-shrink:0;\n  flex-direction:row-reverse;\n}\n\n#uc_unlimited_timeline_elementor_ca261df .ue_timeline_item_spacer{\n  flex:1;\n  flex-shrink:0;\n}\n\n#uc_unlimited_timeline_elementor_ca261df .ue_timeline_item_content_main{\n  flex-grow:1;\n  word-break: break-word;\n  transition: all .3s;\n  position: relative;\n}\n\n#uc_unlimited_timeline_elementor_ca261df .ue_timeline_item_content_main_link{\n  position: absolute;\n  width: 100%;\n  height: 100%;\n  left: 0;\n  top: 0;\n  display: block;\n}\n\n#uc_unlimited_timeline_elementor_ca261df .ue_timeline_item_content{\n  display:flex;\n}\n\n#uc_unlimited_timeline_elementor_ca261df .ue_timeline_item_pointer_spacer{\n  flex-grow:0;\n  flex-shrink:0;\n}\n\n#uc_unlimited_timeline_elementor_ca261df .ue_timeline_item_icon{\n  flex-grow:0;\n  flex-shrink:0;\n}\n\n#uc_unlimited_timeline_elementor_ca261df .ue_timeline_item_pointer{  \n  flex-grow:0;\n  flex-shrink:0;\n  margin-top:0px;\n  position:relative;\n}\n\n#uc_unlimited_timeline_elementor_ca261df .ue_timeline_item .ue_timeline_item_content .ue_timeline_item_pointer .ue_timeline_item_pointer_inside{\n  position:relative;\n  clip-path: polygon(0 50%, 100% 0, 100% 100%);\n  transition: all .3s;\n}\n\n  #uc_unlimited_timeline_elementor_ca261df .ue_timeline_item:last-child .ue_timeline_item_icon_line{\n    display:none;\n  }\n\t\n\n#uc_unlimited_timeline_elementor_ca261df .ue_timeline_item:last-child .ue_timeline_item_content{\n  margin-bottom:0px;\n}\n\n#uc_unlimited_timeline_elementor_ca261df .ue_timeline_item_spacer  {\n  display:none;\n}\n\n\t\n\n#uc_unlimited_timeline_elementor_ca261df .ue_timeline_item_button{\n\tdisplay: flex;\n  \talign-items: center;\n}\n\n#uc_unlimited_timeline_elementor_ca261df .ue_timeline_item_link{\n\tcursor: pointer;\n  \ttransition: all .3s;\n}\n\n   #uc_unlimited_timeline_elementor_ca261df .ue_timeline_item .ue_timeline_item_content .ue_timeline_item_pointer .ue_timeline_item_pointer_inside   {\n     transform: scaleX(-1);\n   }\n\n.ue_timeline_item_title{\n  font-size:21px;\n}\n\n.ue_text_one, .ue_text_two, .ue_text_three{\n  font-size:14px;\n  line-height:1.1em;\n}\n\n.ue_timeline_item_icon_line_mask, .ue_timeline_item_icon_line_offset_mask {\n  width: 100%;\n  height: 0%;\n  max-height: 100%;\n  will-change: height;\n}\n\n#uc_unlimited_timeline_elementor_ca261df .ue_timeline_item_line_icon_holder{\n  position: relative;\n}\n\n#uc_unlimited_timeline_elementor_ca261df .ue_timeline_item_line_floating_icon,\n#uc_unlimited_timeline_elementor_ca261df .ue_timeline_item_line_floating_icon-offset{\n  position: absolute;\n  bottom: 0;\n  left: 50%;\n  transform: translate(-50%, 0%);\n  opacity: 0;\n  display: none;\n    display: none !important;\n  }\n\n#uc_unlimited_timeline_elementor_ca261df .ue_timeline_floating_icon{\n  display:flex;\n  opacity: 1;\n  justify-content:center;\n  align-items:center;\n  line-height:1em;\n  flex-direction:column;\n  transition: all 0.4s ease-in-out;\n  text-align: center;\n}\n  \n#uc_unlimited_timeline_elementor_ca261df .ue_timeline_item_image{\nobject-fit: cover;\n}\n\n#uc_unlimited_timeline_elementor_ca261df .ue_timeline_item_content_inside{\n  position:relative;\n}\n\n#uc_unlimited_timeline_elementor_ca261df .ue_timeline_item_content_main{\n  position:relative;\n  overflow:hidden;\n}\n\n\n@media only screen and (max-width: 768px) {\n  #uc_unlimited_timeline_elementor_ca261df .ue_timeline_item{\n    flex-direction:row-reverse !important;\n  }\n\n  #uc_unlimited_timeline_elementor_ca261df .ue_timeline_item .ue_timeline_item_content{\n   flex-direction:row-reverse !important;\n  }\n  \n  #uc_unlimited_timeline_elementor_ca261df .ue_timeline_item_spacer  {\n    display:none;\n  }\n  \n  #uc_unlimited_timeline_elementor_ca261df .ue_timeline_item .ue_timeline_item_content .ue_timeline_item_pointer .ue_timeline_item_pointer_inside  { \n   clip-path: polygon(0 50%, 100% 0, 100% 100%) !important;\n  }  \n}\n#uc_unlimited_timeline_elementor_ca261df .ue_timeline_item_img_wrapper{\n  display: flex;\n}\n#uc_unlimited_timeline_elementor_ca261df .ue_timeline_item:nth-child(even) .ue_timeline_item_img_wrapper{\n  justify-content: flex-end;\n}\n#uc_unlimited_timeline_elementor_ca261df .ue_timeline_item:nth-child(odd) .ue_timeline_item_img_wrapper{\n  justify-content: flex-start;\n}\n\t\n\n\n\n\n\n\t\n\n\n\n\n\n\t\n\n\n\n\n\n\t\n\n\n\n\n\n\t\n\n\n\n\n\n\t\n\n\n\n\n\n\t\n\n\n\n\n\n\t\n\n\n\n\n\n\t\n\n\n\n\n\n\t\n\n\n\n\n\n\t\n\n\n\n\n\n\t\n\n\n\n\n\n\t\n\n\n\n\n\n\t\n\n\n\n\n\n\t\n\n\n\n\n\n\t\n\n\n\n\n\n\n\n<\/style>\n\n<div id=\"uc_unlimited_timeline_elementor_ca261df\" class=\"uc-items-wrapper \"  >\n  \n<div class=\"ue_timeline_item elementor-repeater-item-cd07857 \" id=\"uc_unlimited_timeline_elementor_ca261df_item1\">\n    <div class=\"ue_timeline_item_content\">\n      \n      <div class=\"ue_timeline_item_content_main\">\n        \n                \n        <div class=\"ue_timeline_item_content_inside\">\n                <div class=\"ue_timeline_item_title\" >What are the mandatory requirements for phases 1 and 2 of the e-invoicing system?<\/div>                <div class=\"ue_timeline_item_text\"><p>The first phase of e-invoicing in KSA requires taxpayers to use electronic solutions or systems to generate e-invoices. They can no longer issue manual invoices. Phase I invoices need to contain the QR code and VAT number on tax invoices if such buyer is registered under the VAT law.<\/p><p>In the first phase, generating invoices in XML, anti-tampering features, UUID, and integration with the ZATCA system is not mandatory.<\/p><p>It is however mandatory in the second phase.<\/p><\/div>\t\n      \t          \n        <\/div>\n              <\/div>\n      \n            \n      <div class=\"ue_timeline_item_pointer_spacer\"><\/div>\n      \n    <\/div>\n  \n    <div class=\"ue_timeline_item_icon\">\n      <div class=\"ue_timeline_item_icon_line_offset\">\n      \t<div class=\"ue_timeline_item_icon_line_offset_mask ue_timeline_item_line_icon_holder\">\n          <div class=\"ue_timeline_item_line_floating_icon-offset ue_timeline_floating_icon\"><i class='fas fa-rocket'><\/i><\/div>\n        <\/div>\n      <\/div>\n      <div class=\"ue_timeline_item_icon_holder\">\n                <i class='far fa-circle'><\/i>                      <\/div>\n      \n      <div class=\"ue_timeline_item_icon_line\">\n      \t<div class=\"ue_timeline_item_icon_line_mask ue_timeline_item_line_icon_holder\">\n          <div class=\"ue_timeline_item_line_floating_icon ue_timeline_floating_icon\"><i class='fas fa-rocket'><\/i><\/div>\n        <\/div>\n      <\/div>\n      \n    <\/div>\n    <div class=\"ue_timeline_item_spacer\">\n        \t<\/div>\n  <\/div>\n\n<div class=\"ue_timeline_item elementor-repeater-item-d6cacf9 \" id=\"uc_unlimited_timeline_elementor_ca261df_item2\">\n    <div class=\"ue_timeline_item_content\">\n      \n      <div class=\"ue_timeline_item_content_main\">\n        \n                \n        <div class=\"ue_timeline_item_content_inside\">\n                <div class=\"ue_timeline_item_title\" >In Phase I, which invoices have to mandatorily contain QR Code?<\/div>                <div class=\"ue_timeline_item_text\"><p>QR code is mandatory for simplified e-invoices for B2C transactions. It is, however, optional for standard e-invoices for B2B and B2G transactions.<\/p><\/div>\t\n      \t          \n        <\/div>\n              <\/div>\n      \n            \n      <div class=\"ue_timeline_item_pointer_spacer\"><\/div>\n      \n    <\/div>\n  \n    <div class=\"ue_timeline_item_icon\">\n      <div class=\"ue_timeline_item_icon_line_offset\">\n      \t<div class=\"ue_timeline_item_icon_line_offset_mask ue_timeline_item_line_icon_holder\">\n          <div class=\"ue_timeline_item_line_floating_icon-offset ue_timeline_floating_icon\"><i class='fas fa-rocket'><\/i><\/div>\n        <\/div>\n      <\/div>\n      <div class=\"ue_timeline_item_icon_holder\">\n                <i class='far fa-circle'><\/i>                      <\/div>\n      \n      <div class=\"ue_timeline_item_icon_line\">\n      \t<div class=\"ue_timeline_item_icon_line_mask ue_timeline_item_line_icon_holder\">\n          <div class=\"ue_timeline_item_line_floating_icon ue_timeline_floating_icon\"><i class='fas fa-rocket'><\/i><\/div>\n        <\/div>\n      <\/div>\n      \n    <\/div>\n    <div class=\"ue_timeline_item_spacer\">\n        \t<\/div>\n  <\/div>\n\n<div class=\"ue_timeline_item elementor-repeater-item-5ede368 \" id=\"uc_unlimited_timeline_elementor_ca261df_item3\">\n    <div class=\"ue_timeline_item_content\">\n      \n      <div class=\"ue_timeline_item_content_main\">\n        \n                \n        <div class=\"ue_timeline_item_content_inside\">\n                <div class=\"ue_timeline_item_title\" >What information should a QR Code contain on a simplified e-invoice?<\/div>                <div class=\"ue_timeline_item_text\"><p>Information to be displayed are the name of the seller, their VAT registration number, timestamp of electronic invoice or electronic credit note or debit note, VAT amount, and the total invoice amount.<\/p><\/div>\t\n      \t          \n        <\/div>\n              <\/div>\n      \n            \n      <div class=\"ue_timeline_item_pointer_spacer\"><\/div>\n      \n    <\/div>\n  \n    <div class=\"ue_timeline_item_icon\">\n      <div class=\"ue_timeline_item_icon_line_offset\">\n      \t<div class=\"ue_timeline_item_icon_line_offset_mask ue_timeline_item_line_icon_holder\">\n          <div class=\"ue_timeline_item_line_floating_icon-offset ue_timeline_floating_icon\"><i class='fas fa-rocket'><\/i><\/div>\n        <\/div>\n      <\/div>\n      <div class=\"ue_timeline_item_icon_holder\">\n                <i class='far fa-circle'><\/i>                      <\/div>\n      \n      <div class=\"ue_timeline_item_icon_line\">\n      \t<div class=\"ue_timeline_item_icon_line_mask ue_timeline_item_line_icon_holder\">\n          <div class=\"ue_timeline_item_line_floating_icon ue_timeline_floating_icon\"><i class='fas fa-rocket'><\/i><\/div>\n        <\/div>\n      <\/div>\n      \n    <\/div>\n    <div class=\"ue_timeline_item_spacer\">\n        \t<\/div>\n  <\/div>\n\n<div class=\"ue_timeline_item elementor-repeater-item-c1e9d89 \" id=\"uc_unlimited_timeline_elementor_ca261df_item4\">\n    <div class=\"ue_timeline_item_content\">\n      \n      <div class=\"ue_timeline_item_content_main\">\n        \n                \n        <div class=\"ue_timeline_item_content_inside\">\n                <div class=\"ue_timeline_item_title\" >Presently our Sales Invoice is generated and issued in PDF format, is there a need to convert it to XML, in Phase I.<\/div>                <div class=\"ue_timeline_item_text\"><p>XML Format or PDF-A3 format with embedded XML has been mandated from Phase II.<\/p><\/div>\t\n      \t          \n        <\/div>\n              <\/div>\n      \n            \n      <div class=\"ue_timeline_item_pointer_spacer\"><\/div>\n      \n    <\/div>\n  \n    <div class=\"ue_timeline_item_icon\">\n      <div class=\"ue_timeline_item_icon_line_offset\">\n      \t<div class=\"ue_timeline_item_icon_line_offset_mask ue_timeline_item_line_icon_holder\">\n          <div class=\"ue_timeline_item_line_floating_icon-offset ue_timeline_floating_icon\"><i class='fas fa-rocket'><\/i><\/div>\n        <\/div>\n      <\/div>\n      <div class=\"ue_timeline_item_icon_holder\">\n                <i class='far fa-circle'><\/i>                      <\/div>\n      \n      <div class=\"ue_timeline_item_icon_line\">\n      \t<div class=\"ue_timeline_item_icon_line_mask ue_timeline_item_line_icon_holder\">\n          <div class=\"ue_timeline_item_line_floating_icon ue_timeline_floating_icon\"><i class='fas fa-rocket'><\/i><\/div>\n        <\/div>\n      <\/div>\n      \n    <\/div>\n    <div class=\"ue_timeline_item_spacer\">\n        \t<\/div>\n  <\/div>\n\n<div class=\"ue_timeline_item elementor-repeater-item-d6644a0 \" id=\"uc_unlimited_timeline_elementor_ca261df_item5\">\n    <div class=\"ue_timeline_item_content\">\n      \n      <div class=\"ue_timeline_item_content_main\">\n        \n                \n        <div class=\"ue_timeline_item_content_inside\">\n                <div class=\"ue_timeline_item_title\" >In which language should Invoices be issued?<\/div>                <div class=\"ue_timeline_item_text\"><p>Arabic is the primary language, and any other language can be used in addition.<\/p><\/div>\t\n      \t          \n        <\/div>\n              <\/div>\n      \n            \n      <div class=\"ue_timeline_item_pointer_spacer\"><\/div>\n      \n    <\/div>\n  \n    <div class=\"ue_timeline_item_icon\">\n      <div class=\"ue_timeline_item_icon_line_offset\">\n      \t<div class=\"ue_timeline_item_icon_line_offset_mask ue_timeline_item_line_icon_holder\">\n          <div class=\"ue_timeline_item_line_floating_icon-offset ue_timeline_floating_icon\"><i class='fas fa-rocket'><\/i><\/div>\n        <\/div>\n      <\/div>\n      <div class=\"ue_timeline_item_icon_holder\">\n                <i class='far fa-circle'><\/i>                      <\/div>\n      \n      <div class=\"ue_timeline_item_icon_line\">\n      \t<div class=\"ue_timeline_item_icon_line_mask ue_timeline_item_line_icon_holder\">\n          <div class=\"ue_timeline_item_line_floating_icon ue_timeline_floating_icon\"><i class='fas fa-rocket'><\/i><\/div>\n        <\/div>\n      <\/div>\n      \n    <\/div>\n    <div class=\"ue_timeline_item_spacer\">\n        \t<\/div>\n  <\/div>\n\n<div class=\"ue_timeline_item elementor-repeater-item-f030302 \" id=\"uc_unlimited_timeline_elementor_ca261df_item6\">\n    <div class=\"ue_timeline_item_content\">\n      \n      <div class=\"ue_timeline_item_content_main\">\n        \n                \n        <div class=\"ue_timeline_item_content_inside\">\n                <div class=\"ue_timeline_item_title\" >Is there a specified format in which Phase I Invoices have to be issued?<\/div>                <div class=\"ue_timeline_item_text\"><p>No specific format is mandated. However, XML Format or PDF-A3 format with embedded XML has been mandated from Phase II.\u00a0<\/p><p>Sample invoices have been provided by ZATCA in this document:\u00a0<\/p><p><span><a href=\"https:\/\/zatca.gov.sa\/en\/E-Invoicing\/Introduction\/Guidelines\/Documents\/E-invoicing_Simplified%20GL.pdf\">https:\/\/zatca.gov.sa\/en\/E-Invoicing\/Introduction\/Guidelines\/Documents\/E-invoicing_Simplified%20GL.pdf<\/a><\/span>.\u00a0<\/p><p><strong><em>(Please refer to Page# 7 &amp; Page# 8)<\/em><\/strong><\/p><\/div>\t\n      \t          \n        <\/div>\n              <\/div>\n      \n            \n      <div class=\"ue_timeline_item_pointer_spacer\"><\/div>\n      \n    <\/div>\n  \n    <div class=\"ue_timeline_item_icon\">\n      <div class=\"ue_timeline_item_icon_line_offset\">\n      \t<div class=\"ue_timeline_item_icon_line_offset_mask ue_timeline_item_line_icon_holder\">\n          <div class=\"ue_timeline_item_line_floating_icon-offset ue_timeline_floating_icon\"><i class='fas fa-rocket'><\/i><\/div>\n        <\/div>\n      <\/div>\n      <div class=\"ue_timeline_item_icon_holder\">\n                <i class='far fa-circle'><\/i>                      <\/div>\n      \n      <div class=\"ue_timeline_item_icon_line\">\n      \t<div class=\"ue_timeline_item_icon_line_mask ue_timeline_item_line_icon_holder\">\n          <div class=\"ue_timeline_item_line_floating_icon ue_timeline_floating_icon\"><i class='fas fa-rocket'><\/i><\/div>\n        <\/div>\n      <\/div>\n      \n    <\/div>\n    <div class=\"ue_timeline_item_spacer\">\n        \t<\/div>\n  <\/div>\n\n<div class=\"ue_timeline_item elementor-repeater-item-3276e2b \" id=\"uc_unlimited_timeline_elementor_ca261df_item7\">\n    <div class=\"ue_timeline_item_content\">\n      \n      <div class=\"ue_timeline_item_content_main\">\n        \n                \n        <div class=\"ue_timeline_item_content_inside\">\n                <div class=\"ue_timeline_item_title\" >What are the contents of a QR code during phase I of KSA e-invoicing?<\/div>                <div class=\"ue_timeline_item_text\"><p>QR Code is a matrix barcode with a pattern of black and white squares. It is machine-readable by a QR code scanner or the camera of smart devices to enable basic validation of electronic invoices and electronic notes.<\/p><p>QR Code must contain 5 mandatory fields as specified by ZATCA in Phase I.\u00a0<\/p><ul><li>\u200b\u200bSeller\u2019s Name<\/li><li>VAT registration number of the seller<\/li><li>Timestamp of the electronic invoice or credit\/ debit note (date and time)<\/li><li>Electronic invoice or credit\/ debit note total (with VAT)<\/li><li>VAT total<\/li><\/ul><\/div>\t\n      \t          \n        <\/div>\n              <\/div>\n      \n            \n      <div class=\"ue_timeline_item_pointer_spacer\"><\/div>\n      \n    <\/div>\n  \n    <div class=\"ue_timeline_item_icon\">\n      <div class=\"ue_timeline_item_icon_line_offset\">\n      \t<div class=\"ue_timeline_item_icon_line_offset_mask ue_timeline_item_line_icon_holder\">\n          <div class=\"ue_timeline_item_line_floating_icon-offset ue_timeline_floating_icon\"><i class='fas fa-rocket'><\/i><\/div>\n        <\/div>\n      <\/div>\n      <div class=\"ue_timeline_item_icon_holder\">\n                <i class='far fa-circle'><\/i>                      <\/div>\n      \n      <div class=\"ue_timeline_item_icon_line\">\n      \t<div class=\"ue_timeline_item_icon_line_mask ue_timeline_item_line_icon_holder\">\n          <div class=\"ue_timeline_item_line_floating_icon ue_timeline_floating_icon\"><i class='fas fa-rocket'><\/i><\/div>\n        <\/div>\n      <\/div>\n      \n    <\/div>\n    <div class=\"ue_timeline_item_spacer\">\n        \t<\/div>\n  <\/div>\n\n<div class=\"ue_timeline_item elementor-repeater-item-5f2f76b \" id=\"uc_unlimited_timeline_elementor_ca261df_item8\">\n    <div class=\"ue_timeline_item_content\">\n      \n      <div class=\"ue_timeline_item_content_main\">\n        \n                \n        <div class=\"ue_timeline_item_content_inside\">\n                <div class=\"ue_timeline_item_title\" >As a business practice, we receive Advances from Customers. Are we required to generate a E Invoice for the advance amount received?<\/div>                <div class=\"ue_timeline_item_text\"><p>A tax invoice must be issued at the time of receiving an advance, with a breakup of taxable value &amp; VAT.<\/p><\/div>\t\n      \t          \n        <\/div>\n              <\/div>\n      \n            \n      <div class=\"ue_timeline_item_pointer_spacer\"><\/div>\n      \n    <\/div>\n  \n    <div class=\"ue_timeline_item_icon\">\n      <div class=\"ue_timeline_item_icon_line_offset\">\n      \t<div class=\"ue_timeline_item_icon_line_offset_mask ue_timeline_item_line_icon_holder\">\n          <div class=\"ue_timeline_item_line_floating_icon-offset ue_timeline_floating_icon\"><i class='fas fa-rocket'><\/i><\/div>\n        <\/div>\n      <\/div>\n      <div class=\"ue_timeline_item_icon_holder\">\n                <i class='far fa-circle'><\/i>                      <\/div>\n      \n      <div class=\"ue_timeline_item_icon_line\">\n      \t<div class=\"ue_timeline_item_icon_line_mask ue_timeline_item_line_icon_holder\">\n          <div class=\"ue_timeline_item_line_floating_icon ue_timeline_floating_icon\"><i class='fas fa-rocket'><\/i><\/div>\n        <\/div>\n      <\/div>\n      \n    <\/div>\n    <div class=\"ue_timeline_item_spacer\">\n        \t<\/div>\n  <\/div>\n\n<div class=\"ue_timeline_item elementor-repeater-item-1bc0938 \" id=\"uc_unlimited_timeline_elementor_ca261df_item9\">\n    <div class=\"ue_timeline_item_content\">\n      \n      <div class=\"ue_timeline_item_content_main\">\n        \n                \n        <div class=\"ue_timeline_item_content_inside\">\n                <div class=\"ue_timeline_item_title\" >Can a E Invoice already generated, be modified or cancelled?<\/div>                <div class=\"ue_timeline_item_text\"><p>Once the invoice is generated, it can neither be modified nor cancelled. In case there is a need to amend the invoice details, either a Credit Note or Debit Note, as the case may be will have to be generated against the issued Invoice.<\/p><p>A fresh invoice with correct particulars can be raised, subsequently.<\/p><\/div>\t\n      \t          \n        <\/div>\n              <\/div>\n      \n            \n      <div class=\"ue_timeline_item_pointer_spacer\"><\/div>\n      \n    <\/div>\n  \n    <div class=\"ue_timeline_item_icon\">\n      <div class=\"ue_timeline_item_icon_line_offset\">\n      \t<div class=\"ue_timeline_item_icon_line_offset_mask ue_timeline_item_line_icon_holder\">\n          <div class=\"ue_timeline_item_line_floating_icon-offset ue_timeline_floating_icon\"><i class='fas fa-rocket'><\/i><\/div>\n        <\/div>\n      <\/div>\n      <div class=\"ue_timeline_item_icon_holder\">\n                <i class='far fa-circle'><\/i>                      <\/div>\n      \n      <div class=\"ue_timeline_item_icon_line\">\n      \t<div class=\"ue_timeline_item_icon_line_mask ue_timeline_item_line_icon_holder\">\n          <div class=\"ue_timeline_item_line_floating_icon ue_timeline_floating_icon\"><i class='fas fa-rocket'><\/i><\/div>\n        <\/div>\n      <\/div>\n      \n    <\/div>\n    <div class=\"ue_timeline_item_spacer\">\n        \t<\/div>\n  <\/div>\n\n<div class=\"ue_timeline_item elementor-repeater-item-fba5a07 \" id=\"uc_unlimited_timeline_elementor_ca261df_item10\">\n    <div class=\"ue_timeline_item_content\">\n      \n      <div class=\"ue_timeline_item_content_main\">\n        \n                \n        <div class=\"ue_timeline_item_content_inside\">\n                <div class=\"ue_timeline_item_title\" >What is the ZATCA prescribed method for data storage\/archiving of invoices & notes<\/div>                <div class=\"ue_timeline_item_text\"><p>The naming convention of the file for data storage\/archive is *VAT Registration (tax registration number) * + Timestamp (date and time at the point of invoice generation) + Invoice Reference Number.<\/p><p>The VAT registration number is the Seller (Supplier) VAT registration number.<\/p><\/div>\t\n      \t          \n        <\/div>\n              <\/div>\n      \n            \n      <div class=\"ue_timeline_item_pointer_spacer\"><\/div>\n      \n    <\/div>\n  \n    <div class=\"ue_timeline_item_icon\">\n      <div class=\"ue_timeline_item_icon_line_offset\">\n      \t<div class=\"ue_timeline_item_icon_line_offset_mask ue_timeline_item_line_icon_holder\">\n          <div class=\"ue_timeline_item_line_floating_icon-offset ue_timeline_floating_icon\"><i class='fas fa-rocket'><\/i><\/div>\n        <\/div>\n      <\/div>\n      <div class=\"ue_timeline_item_icon_holder\">\n                <i class='far fa-circle'><\/i>                      <\/div>\n      \n      <div class=\"ue_timeline_item_icon_line\">\n      \t<div class=\"ue_timeline_item_icon_line_mask ue_timeline_item_line_icon_holder\">\n          <div class=\"ue_timeline_item_line_floating_icon ue_timeline_floating_icon\"><i class='fas fa-rocket'><\/i><\/div>\n        <\/div>\n      <\/div>\n      \n    <\/div>\n    <div class=\"ue_timeline_item_spacer\">\n        \t<\/div>\n  <\/div>\n\n<div class=\"ue_timeline_item elementor-repeater-item-704ea9d \" id=\"uc_unlimited_timeline_elementor_ca261df_item11\">\n    <div class=\"ue_timeline_item_content\">\n      \n      <div class=\"ue_timeline_item_content_main\">\n        \n                \n        <div class=\"ue_timeline_item_content_inside\">\n                <div class=\"ue_timeline_item_title\" >Is it mandatory to have the Invoice numbering in sequence in Phase 1?<\/div>                <div class=\"ue_timeline_item_text\"><p>ZATCA does not permit more than one Invoice sequence in one specific e-invoicing solution unit at any given time. Maintaining more than one sequence is part of ZATCA mandated prohibited functionalities.<\/p><\/div>\t\n      \t          \n        <\/div>\n              <\/div>\n      \n            \n      <div class=\"ue_timeline_item_pointer_spacer\"><\/div>\n      \n    <\/div>\n  \n    <div class=\"ue_timeline_item_icon\">\n      <div class=\"ue_timeline_item_icon_line_offset\">\n      \t<div class=\"ue_timeline_item_icon_line_offset_mask ue_timeline_item_line_icon_holder\">\n          <div class=\"ue_timeline_item_line_floating_icon-offset ue_timeline_floating_icon\"><i class='fas fa-rocket'><\/i><\/div>\n        <\/div>\n      <\/div>\n      <div class=\"ue_timeline_item_icon_holder\">\n                <i class='far fa-circle'><\/i>                      <\/div>\n      \n      <div class=\"ue_timeline_item_icon_line\">\n      \t<div class=\"ue_timeline_item_icon_line_mask ue_timeline_item_line_icon_holder\">\n          <div class=\"ue_timeline_item_line_floating_icon ue_timeline_floating_icon\"><i class='fas fa-rocket'><\/i><\/div>\n        <\/div>\n      <\/div>\n      \n    <\/div>\n    <div class=\"ue_timeline_item_spacer\">\n        \t<\/div>\n  <\/div>\n\n<div class=\"ue_timeline_item elementor-repeater-item-8b19f6a \" id=\"uc_unlimited_timeline_elementor_ca261df_item12\">\n    <div class=\"ue_timeline_item_content\">\n      \n      <div class=\"ue_timeline_item_content_main\">\n        \n                \n        <div class=\"ue_timeline_item_content_inside\">\n                <div class=\"ue_timeline_item_title\" >We use our single Group VAT ID (Registration #) for multiple businesses. In such a case, can we have multiple invoice sequences for each of our businesses?<\/div>                <div class=\"ue_timeline_item_text\"><p>In case invoices are generated by separate businesses on separate EGS units. then, each such unit should generate a single invoice sequence.<\/p><\/div>\t\n      \t          \n        <\/div>\n              <\/div>\n      \n            \n      <div class=\"ue_timeline_item_pointer_spacer\"><\/div>\n      \n    <\/div>\n  \n    <div class=\"ue_timeline_item_icon\">\n      <div class=\"ue_timeline_item_icon_line_offset\">\n      \t<div class=\"ue_timeline_item_icon_line_offset_mask ue_timeline_item_line_icon_holder\">\n          <div class=\"ue_timeline_item_line_floating_icon-offset ue_timeline_floating_icon\"><i class='fas fa-rocket'><\/i><\/div>\n        <\/div>\n      <\/div>\n      <div class=\"ue_timeline_item_icon_holder\">\n                <i class='far fa-circle'><\/i>                      <\/div>\n      \n      <div class=\"ue_timeline_item_icon_line\">\n      \t<div class=\"ue_timeline_item_icon_line_mask ue_timeline_item_line_icon_holder\">\n          <div class=\"ue_timeline_item_line_floating_icon ue_timeline_floating_icon\"><i class='fas fa-rocket'><\/i><\/div>\n        <\/div>\n      <\/div>\n      \n    <\/div>\n    <div class=\"ue_timeline_item_spacer\">\n        \t<\/div>\n  <\/div>\n\n<div class=\"ue_timeline_item elementor-repeater-item-64cc6ed \" id=\"uc_unlimited_timeline_elementor_ca261df_item13\">\n    <div class=\"ue_timeline_item_content\">\n      \n      <div class=\"ue_timeline_item_content_main\">\n        \n                \n        <div class=\"ue_timeline_item_content_inside\">\n                <div class=\"ue_timeline_item_title\" >We supply to both B2B & B2C Customers? Is it permissible to have a separate invoice sequence for each type?<\/div>                <div class=\"ue_timeline_item_text\"><p>ZATCA\u2019s mandatory requirement is to generate a single sequence number from each e-invoice solution unit.\u00a0Since no specific directions are specified with regard to separate invoice sequence for B2B &amp; B2C supplies, it is advisable to follow a single invoice sequence number for EGS unit.<\/p><\/div>\t\n      \t          \n        <\/div>\n              <\/div>\n      \n            \n      <div class=\"ue_timeline_item_pointer_spacer\"><\/div>\n      \n    <\/div>\n  \n    <div class=\"ue_timeline_item_icon\">\n      <div class=\"ue_timeline_item_icon_line_offset\">\n      \t<div class=\"ue_timeline_item_icon_line_offset_mask ue_timeline_item_line_icon_holder\">\n          <div class=\"ue_timeline_item_line_floating_icon-offset ue_timeline_floating_icon\"><i class='fas fa-rocket'><\/i><\/div>\n        <\/div>\n      <\/div>\n      <div class=\"ue_timeline_item_icon_holder\">\n                <i class='far fa-circle'><\/i>                      <\/div>\n      \n      <div class=\"ue_timeline_item_icon_line\">\n      \t<div class=\"ue_timeline_item_icon_line_mask ue_timeline_item_line_icon_holder\">\n          <div class=\"ue_timeline_item_line_floating_icon ue_timeline_floating_icon\"><i class='fas fa-rocket'><\/i><\/div>\n        <\/div>\n      <\/div>\n      \n    <\/div>\n    <div class=\"ue_timeline_item_spacer\">\n        \t<\/div>\n  <\/div>\n\n<div class=\"ue_timeline_item elementor-repeater-item-76e7c33 \" id=\"uc_unlimited_timeline_elementor_ca261df_item14\">\n    <div class=\"ue_timeline_item_content\">\n      \n      <div class=\"ue_timeline_item_content_main\">\n        \n                \n        <div class=\"ue_timeline_item_content_inside\">\n                <div class=\"ue_timeline_item_title\" >We are presently in Phase I. Are we required to send e invoice copies to ZATCA?<\/div>                <div class=\"ue_timeline_item_text\"><p>E-invoices are not required to be sent to ZATCA in Phase I. However, storage and retrieval of invoices issued, should be enabled, as and when ZATCA requires the information.<\/p><\/div>\t\n      \t          \n        <\/div>\n              <\/div>\n      \n            \n      <div class=\"ue_timeline_item_pointer_spacer\"><\/div>\n      \n    <\/div>\n  \n    <div class=\"ue_timeline_item_icon\">\n      <div class=\"ue_timeline_item_icon_line_offset\">\n      \t<div class=\"ue_timeline_item_icon_line_offset_mask ue_timeline_item_line_icon_holder\">\n          <div class=\"ue_timeline_item_line_floating_icon-offset ue_timeline_floating_icon\"><i class='fas fa-rocket'><\/i><\/div>\n        <\/div>\n      <\/div>\n      <div class=\"ue_timeline_item_icon_holder\">\n                <i class='far fa-circle'><\/i>                      <\/div>\n      \n      <div class=\"ue_timeline_item_icon_line\">\n      \t<div class=\"ue_timeline_item_icon_line_mask ue_timeline_item_line_icon_holder\">\n          <div class=\"ue_timeline_item_line_floating_icon ue_timeline_floating_icon\"><i class='fas fa-rocket'><\/i><\/div>\n        <\/div>\n      <\/div>\n      \n    <\/div>\n    <div class=\"ue_timeline_item_spacer\">\n        \t<\/div>\n  <\/div>\n\n<div class=\"ue_timeline_item elementor-repeater-item-9862db1 \" id=\"uc_unlimited_timeline_elementor_ca261df_item15\">\n    <div class=\"ue_timeline_item_content\">\n      \n      <div class=\"ue_timeline_item_content_main\">\n        \n                \n        <div class=\"ue_timeline_item_content_inside\">\n                <div class=\"ue_timeline_item_title\" >Can we use a new invoice sequence, for each financial year or period?<\/div>                <div class=\"ue_timeline_item_text\"><p>ZATCA\u2019s present guidelines does not specify, if Invoice sequence is allowed to break based on change of the year. Hence it is advisable to continue the invoice sequence, into a new financial year or period.<\/p><\/div>\t\n      \t          \n        <\/div>\n              <\/div>\n      \n            \n      <div class=\"ue_timeline_item_pointer_spacer\"><\/div>\n      \n    <\/div>\n  \n    <div class=\"ue_timeline_item_icon\">\n      <div class=\"ue_timeline_item_icon_line_offset\">\n      \t<div class=\"ue_timeline_item_icon_line_offset_mask ue_timeline_item_line_icon_holder\">\n          <div class=\"ue_timeline_item_line_floating_icon-offset ue_timeline_floating_icon\"><i class='fas fa-rocket'><\/i><\/div>\n        <\/div>\n      <\/div>\n      <div class=\"ue_timeline_item_icon_holder\">\n                <i class='far fa-circle'><\/i>                      <\/div>\n      \n      <div class=\"ue_timeline_item_icon_line\">\n      \t<div class=\"ue_timeline_item_icon_line_mask ue_timeline_item_line_icon_holder\">\n          <div class=\"ue_timeline_item_line_floating_icon ue_timeline_floating_icon\"><i class='fas fa-rocket'><\/i><\/div>\n        <\/div>\n      <\/div>\n      \n    <\/div>\n    <div class=\"ue_timeline_item_spacer\">\n        \t<\/div>\n  <\/div>\n\n<div class=\"ue_timeline_item elementor-repeater-item-6aec40e \" id=\"uc_unlimited_timeline_elementor_ca261df_item16\">\n    <div class=\"ue_timeline_item_content\">\n      \n      <div class=\"ue_timeline_item_content_main\">\n        \n                \n        <div class=\"ue_timeline_item_content_inside\">\n                <div class=\"ue_timeline_item_title\" >Our invoices are generated from a global EMR system which means the invoices in KSA will not be in sequence at all. What would be the solution for this?<\/div>                <div class=\"ue_timeline_item_text\"><p>It would be better if you could map a specific sequence, especially for KSA, in your Global EMR system since sequencing is a must in KSA.<\/p><\/div>\t\n      \t          \n        <\/div>\n              <\/div>\n      \n            \n      <div class=\"ue_timeline_item_pointer_spacer\"><\/div>\n      \n    <\/div>\n  \n    <div class=\"ue_timeline_item_icon\">\n      <div class=\"ue_timeline_item_icon_line_offset\">\n      \t<div class=\"ue_timeline_item_icon_line_offset_mask ue_timeline_item_line_icon_holder\">\n          <div class=\"ue_timeline_item_line_floating_icon-offset ue_timeline_floating_icon\"><i class='fas fa-rocket'><\/i><\/div>\n        <\/div>\n      <\/div>\n      <div class=\"ue_timeline_item_icon_holder\">\n                <i class='far fa-circle'><\/i>                      <\/div>\n      \n      <div class=\"ue_timeline_item_icon_line\">\n      \t<div class=\"ue_timeline_item_icon_line_mask ue_timeline_item_line_icon_holder\">\n          <div class=\"ue_timeline_item_line_floating_icon ue_timeline_floating_icon\"><i class='fas fa-rocket'><\/i><\/div>\n        <\/div>\n      <\/div>\n      \n    <\/div>\n    <div class=\"ue_timeline_item_spacer\">\n        \t<\/div>\n  <\/div>\n \n<\/div>\n<!-- end Unlimited Timeline -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Frequently Asked Questions Phase I of KSA e-Invoicing What are the mandatory requirements for phases 1 and 2 of the e-invoicing system? The first phase of e-invoicing in KSA requires taxpayers to use electronic solutions or systems to generate e-invoices. They can no longer issue manual invoices. Phase I invoices need to contain the QR [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_eb_attr":"","footnotes":""},"doc_category":[119],"doc_tag":[],"knowledge_base":[],"class_list":["post-11356","docs","type-docs","status-publish","hentry","doc_category-faq"],"year_month":"2026-07","word_count":1719,"total_views":"1492","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"admin","author_nicename":"vita","author_url":"https:\/\/vita-xpro.com\/ar\/author\/vita\/"},"doc_category_info":[{"term_name":"FAQ","term_url":"https:\/\/vita-xpro.com\/ar\/docs-category\/faq\/"}],"doc_tag_info":[],"_links":{"self":[{"href":"https:\/\/vita-xpro.com\/ar\/wp-json\/wp\/v2\/docs\/11356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vita-xpro.com\/ar\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/vita-xpro.com\/ar\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/vita-xpro.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vita-xpro.com\/ar\/wp-json\/wp\/v2\/comments?post=11356"}],"version-history":[{"count":12,"href":"https:\/\/vita-xpro.com\/ar\/wp-json\/wp\/v2\/docs\/11356\/revisions"}],"predecessor-version":[{"id":11972,"href":"https:\/\/vita-xpro.com\/ar\/wp-json\/wp\/v2\/docs\/11356\/revisions\/11972"}],"wp:attachment":[{"href":"https:\/\/vita-xpro.com\/ar\/wp-json\/wp\/v2\/media?parent=11356"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/vita-xpro.com\/ar\/wp-json\/wp\/v2\/doc_category?post=11356"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/vita-xpro.com\/ar\/wp-json\/wp\/v2\/doc_tag?post=11356"},{"taxonomy":"knowledge_base","embeddable":true,"href":"https:\/\/vita-xpro.com\/ar\/wp-json\/wp\/v2\/knowledge_base?post=11356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}